{"id":152,"date":"2021-05-21T13:45:13","date_gmt":"2021-05-21T16:45:13","guid":{"rendered":"https:\/\/norfish.ca\/?page_id=152"},"modified":"2021-05-21T13:45:13","modified_gmt":"2021-05-21T16:45:13","slug":"request-tags","status":"publish","type":"page","link":"https:\/\/norfish.ca\/index.php\/request-tags\/","title":{"rendered":"Request Tags"},"content":{"rendered":"<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f151-o1\" lang=\"en-CA\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/152#wpcf7-f151-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"151\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_CA\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f151-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><script type=\"text\/javascript\">\nadd_filter( 'wpcf7_validate_email*', 'custom_email_confirmation_validation_filter', 20, 2 );  \nfunction custom_email_confirmation_validation_filter( $result, $tag ) {\n  if ( 'telephone-number' == $tag->name ) {\n    if ( !isset( $_POST['email-address\"] && !isset($_POST['telephone-number'] ) {\n      $result->invalidate( $tag, \"You need either an e-mail address or a phone number\" );\n    }\n  } \n  return $result;\n}\n<\/script><label> Your name:<br \/>\n    <span class=\"wpcf7-form-control-wrap contact-name\"><input type=\"text\" name=\"contact-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Your license Number<br \/>\n    <span class=\"wpcf7-form-control-wrap license-number\"><input type=\"text\" name=\"license-number\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> How to contact you?<\/label><span class=\"wpcf7-form-control-wrap contact-method\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><input type=\"radio\" name=\"contact-method\" value=\"Email\" checked=\"checked\" \/><span class=\"wpcf7-list-item-label\">Email<\/span><\/span><span class=\"wpcf7-list-item\"><input type=\"radio\" name=\"contact-method\" value=\"Telephone\" \/><span class=\"wpcf7-list-item-label\">Telephone<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"radio\" name=\"contact-method\" value=\"Text\" \/><span class=\"wpcf7-list-item-label\">Text<\/span><\/span><\/span><\/span><\/p>\n<p><label> Either Your email address...<br \/>\n    <span class=\"wpcf7-form-control-wrap email-address\"><input type=\"email\" name=\"email-address\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-email\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> ...or your Phone number.<br \/>\n    <span class=\"wpcf7-form-control-wrap telephone-number\"><input type=\"tel\" name=\"telephone-number\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-tel\" aria-invalid=\"false\" \/><\/span>  <\/label><\/p>\n<p><label> Species for replacement tag<br \/>\n    <span class=\"wpcf7-form-control-wrap tag-species\"><select name=\"tag-species\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"\">---<\/option><option value=\"Spring Herring\">Spring Herring<\/option><option value=\"Crab\">Crab<\/option><option value=\"Lobster\">Lobster<\/option><option value=\"Fall Herring\">Fall Herring<\/option><\/select><\/span> <\/label><\/p>\n<p><label> Number of replacement tags needed<br \/>\n    <span class=\"wpcf7-form-control-wrap tag-count\"><input type=\"number\" name=\"tag-count\" value=\"1\" class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1\" max=\"10\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Tag numbers lost or destroyed (enter all needed)<br \/>\n    <span class=\"wpcf7-form-control-wrap tag-numbers\"><input type=\"text\" name=\"tag-numbers\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Extra information or message (optional)<br \/>\n    <span class=\"wpcf7-form-control-wrap extra-message\"><textarea name=\"extra-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"Submit\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/pages\/152"}],"collection":[{"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":4,"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/pages\/152\/revisions"}],"predecessor-version":[{"id":156,"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/pages\/152\/revisions\/156"}],"wp:attachment":[{"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/media?parent=152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/categories?post=152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/norfish.ca\/index.php\/wp-json\/wp\/v2\/tags?post=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}